{"id":11435,"date":"2023-03-18T16:01:36","date_gmt":"2023-03-18T15:01:36","guid":{"rendered":"https:\/\/oliviaoged.com\/cart\/"},"modified":"2024-07-06T08:00:02","modified_gmt":"2024-07-06T07:00:02","slug":"cart","status":"publish","type":"page","link":"https:\/\/oliviaoged.com\/en\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"bwfblock_default_font":"","_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11435","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart - Beautiful Books French<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oliviaoged.com\/en\/cart\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Beautiful Books French\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oliviaoged.com\/en\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"Beautiful Books French\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-06T07:00:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/cart\\\/\",\"url\":\"https:\\\/\\\/oliviaoged.com\\\/cart\\\/\",\"name\":\"Cart - Beautiful Books French\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#website\"},\"datePublished\":\"2023-03-18T15:01:36+00:00\",\"dateModified\":\"2024-07-06T07:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/cart\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oliviaoged.com\\\/cart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/cart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oliviaoged.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#website\",\"url\":\"https:\\\/\\\/oliviaoged.com\\\/\",\"name\":\"Beautiful Books French\",\"description\":\"\u00e0 la confluence de la foi et la pens\u00e9e\",\"publisher\":{\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oliviaoged.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#organization\",\"name\":\"Beautiful Books French\",\"url\":\"https:\\\/\\\/oliviaoged.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oliviaoged.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/OLIVIAOGEDSMALLER.png\",\"contentUrl\":\"https:\\\/\\\/oliviaoged.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/OLIVIAOGEDSMALLER.png\",\"width\":399,\"height\":223,\"caption\":\"Beautiful Books French\"},\"image\":{\"@id\":\"https:\\\/\\\/oliviaoged.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Beautiful Books French","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oliviaoged.com\/en\/cart\/","og_locale":"en_GB","og_type":"article","og_title":"Cart - Beautiful Books French","og_url":"https:\/\/oliviaoged.com\/en\/cart\/","og_site_name":"Beautiful Books French","article_modified_time":"2024-07-06T07:00:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oliviaoged.com\/cart\/","url":"https:\/\/oliviaoged.com\/cart\/","name":"Cart - Beautiful Books French","isPartOf":{"@id":"https:\/\/oliviaoged.com\/#website"},"datePublished":"2023-03-18T15:01:36+00:00","dateModified":"2024-07-06T07:00:02+00:00","breadcrumb":{"@id":"https:\/\/oliviaoged.com\/cart\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oliviaoged.com\/cart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oliviaoged.com\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oliviaoged.com\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/oliviaoged.com\/#website","url":"https:\/\/oliviaoged.com\/","name":"Beautiful Books French","description":"at the intersection of faith and reason","publisher":{"@id":"https:\/\/oliviaoged.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oliviaoged.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/oliviaoged.com\/#organization","name":"Beautiful Books French","url":"https:\/\/oliviaoged.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/oliviaoged.com\/#\/schema\/logo\/image\/","url":"https:\/\/oliviaoged.com\/wp-content\/uploads\/2016\/10\/OLIVIAOGEDSMALLER.png","contentUrl":"https:\/\/oliviaoged.com\/wp-content\/uploads\/2016\/10\/OLIVIAOGEDSMALLER.png","width":399,"height":223,"caption":"Beautiful Books French"},"image":{"@id":"https:\/\/oliviaoged.com\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"_jetpack_related_posts_cache":["a:1:{s:32:\"bfc62710165ed7b51223b165689d40a3\";a:2:{s:7:\"expires\";i:1706257171;s:7:\"payload\";a:0:{}}}"],"uag_migration_processed":["1"],"_edit_lock":["1739216263:6"],"_uag_css_file_name":["uag-css-11435.css"],"_uag_js_file_name":["uag-js-11435.js"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"astra_style_timestamp_css":["1780332907"],"_uag_page_assets":["a:9:{s:3:\"css\";s:173873:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-3c8fcc0c.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-3c8fcc0c .wp-block-uagb-image__figure{align-items: center;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3c8fcc0c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-3c8fcc0c.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.uagb-block-7ad97637.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-7ad97637.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-7ad97637:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-7ad97637:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-7ad97637:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7ad97637:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-7ad97637 .uagb-post__inner-wrap{background: #f6f6f6;text-align: left;}.uagb-block-7ad97637 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-7ad97637 .uagb-post__image {padding-bottom: 15px;}.uagb-block-7ad97637 .uagb-post__title{padding-bottom: 15px;}.uagb-block-7ad97637 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-7ad97637 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-7ad97637 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-7ad97637.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7ad97637.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-7ad97637.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7ad97637 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-7ad97637 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-7ad97637.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-7ad97637.is_carousel .uagb-post__inner-wrap{background-color: #f6f6f6;}.uagb-block-7ad97637 .slick-arrow{border-color: #000;border-width: 0px;border-radius: 0px;}.uagb-block-7ad97637 .slick-arrow span{color: #000;font-size: 24px;width: 24px;height: 24px;}.uagb-block-7ad97637 .slick-arrow svg{fill: #000;width: 24px;height: 24px;}.uagb-block-7ad97637.uagb-post-grid ul.slick-dots li.slick-active button:before{color: #000;}.uagb-block-7ad97637.uagb-slick-carousel ul.slick-dots li button:before{color: #000;}.uagb-block-7ad97637 .slick-dots{margin-top: 20px !important;}@media only screen and (max-width: 976px) {.uagb-block-7ad97637.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-7ad97637.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7ad97637.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-7ad97637.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-7ad97637 .uagb-post__cta a{border-style: none;}.uagb-block-7ad97637 .slick-dots{margin-top:  !important;}}@media only screen and (max-width: 767px) {.uagb-block-7ad97637.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-7ad97637.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-7ad97637:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-7ad97637.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-7ad97637.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-7ad97637 .slick-dots{margin-top:  !important;}}.uagb-block-381ee082.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-381ee082.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-381ee082:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-381ee082:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-381ee082:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-381ee082:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-381ee082:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-381ee082:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-381ee082 .uagb-post__inner-wrap{background: #f6f6f6;text-align: left;}.uagb-block-381ee082 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-381ee082 .uagb-post__image {padding-bottom: 15px;}.uagb-block-381ee082 .uagb-post__title{padding-bottom: 15px;}.uagb-block-381ee082 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-381ee082 .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-381ee082 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-381ee082.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-381ee082.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-381ee082.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-381ee082 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-381ee082 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-381ee082.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-381ee082.is_carousel .uagb-post__inner-wrap{background-color: #f6f6f6;}.uagb-block-381ee082 .slick-arrow{border-color: #000;border-width: 0px;border-radius: 0px;}.uagb-block-381ee082 .slick-arrow span{color: #000;font-size: 24px;width: 24px;height: 24px;}.uagb-block-381ee082 .slick-arrow svg{fill: #000;width: 24px;height: 24px;}.uagb-block-381ee082.uagb-post-grid ul.slick-dots li.slick-active button:before{color: #000;}.uagb-block-381ee082.uagb-slick-carousel ul.slick-dots li button:before{color: #000;}.uagb-block-381ee082 .slick-dots{margin-top: 20px !important;}@media only screen and (max-width: 976px) {.uagb-block-381ee082.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-381ee082.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-381ee082:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-381ee082:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-381ee082.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-381ee082.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-381ee082 .uagb-post__cta a{border-style: none;}.uagb-block-381ee082 .slick-dots{margin-top:  !important;}}@media only screen and (max-width: 767px) {.uagb-block-381ee082.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-381ee082.is-grid.uagb-post__items{row-gap: 20px;column-gap: 20px;}.uagb-block-381ee082:not(.is-grid).uagb-post__items article{padding-right: 10px;padding-left: 10px;margin-bottom: 20px;}.uagb-block-381ee082:not(.is-grid).uagb-post__items{margin-right: -10px;margin-left: -10px;}.uagb-block-381ee082.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-381ee082.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-381ee082 .slick-dots{margin-top:  !important;}}.uagb-block-09cf852e.uagb-lottie__outer-wrap{overflow: hidden;outline: none;}.uagb-block-09cf852e.uagb-lottie__left{margin-right: auto !important;margin-left: 0px !important;}.uagb-block-09cf852e.uagb-lottie__right{margin-left: auto !important;margin-right: 0px !important;}.uagb-block-09cf852e.uagb-lottie__center{margin: 0 auto !important;}.wp-block-uagb-blockquote{padding:0;margin:0 auto;-webkit-box-sizing:border-box;box-sizing:border-box}.wp-block-uagb-blockquote .uagb-blockquote__content,.wp-block-uagb-blockquote cite.uagb-blockquote__author{display:block;font-style:normal}.wp-block-uagb-blockquote cite.uagb-blockquote__author,.wp-block-uagb-blockquote .uagb-blockquote__author{-ms-flex-item-align:center;align-self:center}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation blockquote.uagb-blockquote{margin:0;padding:0;border:0;outline:0;font-size:100%;vertical-align:baseline;background:rgba(0,0,0,0);quotes:none;border-left:0 none;border-right:0 none;border-top:0 none;border-bottom:0 none;font-style:normal}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{display:inline-flex;float:unset}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap .uagb-blockquote__icon{padding:0;margin-right:0;margin-bottom:0}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2 .uagb-blockquote__icon-wrap{display:inline-block;float:left}.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{background-color:#1da1f2;border-radius:100em;color:#fff}.wp-block-uagb-blockquote .uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote .uagb-blockquote__tweet-text a.uagb-blockquote__tweet-button{padding:10px 14px}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet.uagb-blockquote__align-center .uagb-blockquote footer,.wp-block-uagb-blockquote .uagb-blockquote__align-center .uagb-blockquote footer{display:block;text-align:center}.wp-block-uagb-blockquote .uagb-blockquote__align-center .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote .uagb-blockquote__align-center a.uagb-blockquote__tweet-button{display:block;text-align:center;margin:0 auto;-ms-flex-item-align:center;align-self:center}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet .uagb-blockquote footer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-pack:justify;-webkit-justify-content:space-between;-ms-flex-pack:justify;justify-content:space-between}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{width:auto;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{position:absolute;top:50%;left:-0.8em;border:solid .5em rgba(0,0,0,0);border-right-color:#1da1f2;transform:translateY(-50%) scale(1, 0.65);transition:.2s;content:\"\";-webkit-transform:translateY(-50%) scale(1, 0.65);-ms-transform:translateY(-50%) scale(1, 0.65);-webkit-transition:.2s;-o-transition:.2s}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation blockquote.uagb-blockquote{vertical-align:baseline;padding:0;margin:0;background:rgba(0,0,0,0);border:0 none;outline:0;font-size:100%;font-style:normal;quotes:none}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation .uagb-blockquote__icon{position:relative;display:inline-block;z-index:1;padding:10px;margin-right:10px;border-radius:100%;float:left}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{display:inherit;width:inherit;height:inherit}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2.uagb-blockquote__align-right .uagb-blockquote__icon{display:inline-block;float:right}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2 .uagb-blockquote__icon{display:inline-block;float:left}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_1 .uagb-blockquote__icon{display:inline-flex;float:unset}.wp-block-uagb-blockquote blockquote.uagb-blockquote{padding:0;margin:0}.wp-block-uagb-blockquote .uagb-blockquote__style-style_2 .uagb-blockquote__icon{display:inline-block;float:left;text-align:left}.wp-block-uagb-blockquote .uagb-blockquote__separator-parent{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;justify-content:flex-start;-js-display:flex;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote footer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;justify-content:space-between;-webkit-box-pack:justify;-webkit-justify-content:space-between;-ms-flex-pack:justify}.wp-block-uagb-blockquote .uagb-blockquote a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.wp-block-uagb-blockquote .uagb-blockquote a.uagb-blockquote__tweet-button{position:relative;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;align-self:center;width:-webkit-max-content;width:-moz-max-content;width:max-content;padding:0;background-color:rgba(0,0,0,0);color:#1da1f2;line-height:1;transition:.2s;-webkit-transition:.2s;-o-transition:.2s;-webkit-align-self:flex-end;-ms-flex-item-align:center}.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button svg{align-self:center;vertical-align:middle;width:15px;height:15px;fill:#fff}.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button svg{font-style:normal}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon a.uagb-blockquote__tweet-button svg{margin-right:0}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon a.uagb-blockquote__tweet-button{padding:8px}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote.uagb-blockquote__tweet-text a.uagb-blockquote__tweet-button{padding:10px 14px}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{padding:10px 0}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{background-color:#1da1f2;border-radius:100em;color:#fff}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{position:absolute;top:50%;left:-0.8em;border:solid .5em rgba(0,0,0,0);border-right-color:#1da1f2;transform:translateY(-50%) scale(1, 0.65);transition:.2s;content:\"\";-webkit-transform:translateY(-50%) scale(1, 0.65);-ms-transform:translateY(-50%) scale(1, 0.65);-webkit-transition:.2s;-o-transition:.2s}.wp-block-uagb-blockquote.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{right:-0.8em;left:auto;transform:translateY(-50%) scale(1, 0.65) rotate(180deg);-webkit-transform:translateY(-50%) scale(1, 0.65) rotate(180deg);-ms-transform:translateY(-50%) scale(1, 0.65) rotate(180deg)}.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet.uagb-blockquote__align-center .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote footer{display:block;text-align:center}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote.uagb-blockquote__align-center a.uagb-blockquote__tweet-button{display:block;align-self:center;margin:0 auto;text-align:center;-ms-flex-item-align:center}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet.uagb-blockquote__align-right .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote footer{flex-direction:row-reverse}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;flex-direction:row;align-self:center;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap img{width:50px;height:50px;border-radius:100%;object-fit:cover}.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-left .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{justify-content:flex-end;-webkit-box-pack:flex-end;-ms-flex-pack:flex-end;-webkit-justify-content:flex-end;-moz-box-pack:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__align-left .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{justify-content:flex-start;-webkit-box-pack:flex-start;-ms-flex-pack:flex-start;-webkit-justify-content:flex-start;-moz-box-pack:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:unset;-webkit-box-pack:unset;-ms-flex-pack:unset;-webkit-justify-content:unset;-moz-box-pack:unset}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{flex-direction:column;width:100%;-webkit-flex-direction:column;-ms-flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top .uagb-blockquote__author{width:inherit}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{width:auto}.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{text-align:right;align-items:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{text-align:center;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{-webkit-flex-direction:row-reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse;justify-content:flex-end}@media only screen and (max-width: 976px){.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{width:100%}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__with-tweet .uagb-blockquote footer{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-self:flex-start;-ms-flex-item-align:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-start;align-self:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right.uagb-blockquote__with-tweet .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-left.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote .uagb-blockquote__align-right.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{-ms-flex-item-align:flex-start;align-self:flex-start}}@media screen and (max-width: 767px){.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author{width:100%}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__with-tweet .uagb-blockquote footer{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-self:flex-start;-ms-flex-item-align:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-start;align-self:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right.uagb-blockquote__with-tweet .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-left.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote .uagb-blockquote__align-right.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{-ms-flex-item-align:flex-start;align-self:flex-start}}.uagb-block-b4075b93 .uagb-blockquote__content{font-style: italic;font-size: 18px;line-height: 1.5em;margin-bottom: 25px;text-align: left;}.uagb-block-b4075b93 cite.uagb-blockquote__author{color: #888888;text-align: left;}.uagb-block-b4075b93 .uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-b4075b93.uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-b4075b93 .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-b4075b93 .uagb-blockquote__skin-quotation .uagb-blockquote__icon{width: 25px;height: 25px;}.uagb-block-b4075b93.uagb-blockquote__skin-quotation .uagb-blockquote__icon{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-b4075b93.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{width: 25px;height: 25px;fill: #3d3d3d;}.uagb-block-b4075b93.uagb-blockquote__style-style_1 .uagb-blockquote{text-align: left;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap img{width: 40px;height: 40px;border-radius: 100%;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;}.uagb-block-b4075b93 .uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{fill: #3d3d3d;width: 25px;height: 25px;}.uagb-block-b4075b93.uagb-blockquote__align-center blockquote.uagb-blockquote{text-align: left;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{color: #1DA1F2;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button svg{fill: #1DA1F2;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-b4075b93 .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-b4075b93 a.uagb-blockquote__tweet-button svg{width: 15px;height: 15px;}.uagb-block-b4075b93.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button svg{margin-right: 10px;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-b4075b93.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-b4075b93 .uagb-blockquote a.uagb-blockquote__tweet-button{font-size: 15px;}@media only screen and (max-width: 976px) {.uagb-block-b4075b93 .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap img{width: 35px;height: 35px;border-radius: 100%;}.uagb-block-b4075b93.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-b4075b93 .uagb-blockquote__content{margin-bottom: 20px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-b4075b93 .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap img{width: 30px;height: 30px;border-radius: 100%;}.uagb-block-b4075b93.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-b4075b93 .uagb-blockquote__content{margin-bottom: 15px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-b4075b93 .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}.uagb-block-58723bfe.is-grid .uagb-post__inner-wrap{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-58723bfe.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: -20px;margin-right: -20px;margin-top: -20px;}.uagb-block-58723bfe:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 20px;}.uagb-block-58723bfe:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 20px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 20px;}.uagb-block-58723bfe:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -3px;margin-left: -3px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__items article{padding-right: 3px;padding-left: 3px;margin-bottom: 20px;}.uagb-block-58723bfe:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 20px;margin-right: 20px;}.uagb-block-58723bfe .uagb-post__inner-wrap{background: #4a4646;text-align: left;}.uagb-block-58723bfe .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-58723bfe .uagb-post__image {padding-bottom: 15px;}.uagb-block-58723bfe .uagb-post__title{padding-bottom: 15px;}.uagb-block-58723bfe .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-58723bfe .uagb-post__excerpt{padding-bottom: 25px;}.uagb-block-58723bfe .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-58723bfe.is-grid.uagb-post__items{row-gap: 6px;column-gap: 20px;}.uagb-block-58723bfe.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-58723bfe.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-58723bfe .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-58723bfe .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-58723bfe.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: ;0: none;border-style: none;}.uagb-block-58723bfe.is_carousel .uagb-post__inner-wrap{background-color: #4a4646;}.uagb-block-58723bfe .slick-arrow{border-color: #000;border-width: 0px;border-radius: 0px;}.uagb-block-58723bfe .slick-arrow span{color: #000;font-size: 24px;width: 24px;height: 24px;}.uagb-block-58723bfe .slick-arrow svg{fill: #000;width: 24px;height: 24px;}.uagb-block-58723bfe.uagb-post-grid ul.slick-dots li.slick-active button:before{color: #000;}.uagb-block-58723bfe.uagb-slick-carousel ul.slick-dots li button:before{color: #000;}.uagb-block-58723bfe .slick-dots{margin-top: 20px !important;}@media only screen and (max-width: 976px) {.uagb-block-58723bfe.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-58723bfe.is-grid.uagb-post__items{row-gap: 6px;column-gap: 20px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__items article{padding-right: 3px;padding-left: 3px;margin-bottom: 20px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__items{margin-right: -3px;margin-left: -3px;}.uagb-block-58723bfe.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-58723bfe.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-58723bfe .uagb-post__cta a{border-style: none;}.uagb-block-58723bfe .slick-dots{margin-top:  !important;}}@media only screen and (max-width: 767px) {.uagb-block-58723bfe.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-58723bfe.is-grid.uagb-post__items{row-gap: 6px;column-gap: 20px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__items article{padding-right: 3px;padding-left: 3px;margin-bottom: 20px;}.uagb-block-58723bfe:not(.is-grid).uagb-post__items{margin-right: -3px;margin-left: -3px;}.uagb-block-58723bfe.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-58723bfe.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-58723bfe .slick-dots{margin-top:  !important;}}\ufeff.wp-block-uagb-image-gallery{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;-webkit-justify-content:center;justify-content:center;flex-direction:column}.spectra-image-gallery *{box-sizing:border-box}.spectra-image-gallery__layout--grid{display:-moz-grid;display:-ms-grid;display:grid;grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--grid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--isogrid-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--isogrid+.spectra-image-gallery__control-wrapper .spectra-image-gallery__control-arrows:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__layout--masonry-col-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--carousel{width:100%}.spectra-image-gallery__layout--carousel .slick-initialized{visibility:visible}.spectra-image-gallery__layout--carousel .slick-track{display:flex;align-items:center}.spectra-image-gallery__layout--carousel .slick-slide .spectra-image-gallery__media-wrapper{display:block !important}.spectra-image-gallery__layout--carousel .slick-dots{padding:0;position:relative !important}.spectra-image-gallery__layout--carousel .slick-dots li button{padding:0}.spectra-image-gallery__layout--carousel .uagb-slick-carousel{padding:0}.spectra-image-gallery__layout--tiled{position:relative;display:grid;grid-auto-flow:dense;min-height:0;min-width:0}.spectra-image-gallery__layout--tiled-col-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__media{position:relative;overflow:hidden;-webkit-transition:box-shadow .25s;-moz-transition:box-shadow .25s;-o-transition:box-shadow .25s;transition:box-shadow .25s}.spectra-image-gallery__media--flagged{cursor:not-allowed}.spectra-image-gallery__media--clickable{cursor:pointer}.spectra-image-gallery__media--grid{aspect-ratio:1}.spectra-image-gallery__media--masonry{width:100%}.spectra-image-gallery__media--carousel{width:100%}.spectra-image-gallery__media--tiled{aspect-ratio:1;display:flex;align-items:center;justify-content:center}.spectra-image-gallery__media--tiled-wide,.spectra-image-gallery__media--tiled-tall{aspect-ratio:unset;width:100%;height:100%}.spectra-image-gallery__media--tiled picture{width:100%;height:100%}.spectra-image-gallery__media-sizer{aspect-ratio:1}.spectra-image-gallery__media-wrapper{position:relative}.spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__control-focus{opacity:.25}.spectra-image-gallery__media-thumbnail{vertical-align:middle;-webkit-transition:filter .5s,transform .5s;-moz-transition:filter .5s,transform .5s;-o-transition:filter .5s,transform .5s;transition:filter .5s,transform .5s}.spectra-image-gallery__media-thumbnail--grid{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail--masonry{width:100%}.spectra-image-gallery__media-thumbnail--carousel{width:100%}.spectra-image-gallery__media-thumbnail--tiled{width:100% !important;height:100% !important;-o-object-fit:cover;object-fit:cover}.spectra-image-gallery__media-thumbnail-blurrer{position:absolute;top:0;left:0;width:100% !important;height:100% !important;-webkit-transition:box-shadow .25s,-webkit-backdrop-filter .5s;-moz-transition:box-shadow .25s,backdrop-filter .5s;-o-transition:box-shadow .25s,backdrop-filter .5s;transition:box-shadow .25s,backdrop-filter .5s}.spectra-image-gallery__media-thumbnail-caption{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__media-thumbnail-caption--overlay{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;height:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption--bar-inside{width:100%;overflow:hidden;padding:1em;max-height:90%}.spectra-image-gallery__media-thumbnail-caption--bar-outside{width:100%;overflow:hidden;padding:1em}.spectra-image-gallery__media-thumbnail-caption-wrapper{-webkit-transition:background-color .25s;-moz-transition:background-color .25s;-o-transition:background-color .25s;transition:background-color .25s}.spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{position:absolute;top:0;left:0;width:100%;height:100%}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{position:absolute;top:0;left:0;width:100%;height:100%;display:flex;overflow:hidden}.spectra-image-gallery__media-thumbnail-caption-wrapper--bar-outside{position:relative;width:100%;overflow:hidden}.spectra-image-gallery__control-wrapper{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;width:100%;justify-content:center}.spectra-image-gallery__control-arrows{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;background-color:rgba(0,0,0,0);padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-arrows:disabled{opacity:.25;cursor:initial}.spectra-image-gallery__control-arrows:focus{background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-arrows--grid{border:none}.spectra-image-gallery__control-arrows svg{-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots{display:-ms-flex;display:-moz-flex;display:-webkit-flex;display:flex;align-items:center;padding:0 !important;margin:0 !important}.spectra-image-gallery__control-dots li{position:relative;display:inline-block;width:20px;height:20px;margin:0;padding:0;cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li:hover{transform:scale(1.5);background-color:rgba(0,0,0,0)}.spectra-image-gallery__control-dots li button{font-size:0;line-height:0;display:block;box-sizing:border-box;width:20px;height:20px;padding:5px;cursor:pointer;color:rgba(0,0,0,0);border:0;outline:none;background:rgba(0,0,0,0);-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li button::before{font-family:none;font-size:30px;line-height:20px;position:absolute;top:0;left:0;width:20px;height:20px;content:\"\u2022\";text-align:center;opacity:.25;-webkit-font-smoothing:antialiased;-moz-osx-font-smoothing:grayscale;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-dots li.spectra-image-gallery__control-dot--active button::before{opacity:.75}.spectra-image-gallery__control-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.spectra-image-gallery__control-loader div{border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.spectra-image-gallery__control-loader div.spectra-image-gallery__control-loader--2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.spectra-image-gallery__control-button{cursor:pointer;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-button.disabled{opacity:.25;pointer-events:none}.spectra-image-gallery__control-focus{cursor:pointer;position:absolute;box-sizing:content-box !important;top:0;right:0;width:1.5em;height:1.5em;padding:.5em;background-color:rgba(0,0,0,0);border:none;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-focus:hover{opacity:1 !important}.spectra-image-gallery__control-focus svg{fill:#fff;filter:drop-shadow(1px 1px 1px rgba(0, 0, 0, 0.5))}.spectra-image-gallery__control-lightbox{position:fixed;top:0;left:0;width:100vw !important;max-width:100vw !important;height:100vh !important;max-height:100vh !important;display:flex;flex-direction:column;opacity:0;-webkit-transition-property:opacity;-moz-transition-property:opacity;-o-transition-property:opacity;transition-property:opacity;z-index:999999999 !important;outline:none;margin-block-start:0;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--main{width:100%;flex:1}.spectra-image-gallery__control-lightbox--main .swiper-slide{height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center}.spectra-image-gallery__control-lightbox--main .swiper-slide img{display:block;max-height:70%;max-width:80%}.spectra-image-gallery__control-lightbox--caption{position:absolute;bottom:0;left:0;width:100%;display:flex;align-items:center;justify-content:center;text-align:center}.spectra-image-gallery__control-lightbox--editor-link{-webkit-transition-property:color;-moz-transition-property:color;-o-transition-property:color;transition-property:color;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails{width:75%}.spectra-image-gallery__control-lightbox--thumbnails-wrapper{width:100%}.spectra-image-gallery__control-lightbox--thumbnails .swiper-wrapper{height:150px}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide{cursor:pointer;height:100%;display:flex;flex-direction:column;align-items:center;justify-content:center;opacity:.5;transform:scale(75%);-webkit-transition-property:opacity,transform;-moz-transition-property:opacity,transform;-o-transition-property:opacity,transform;transition-property:opacity,transform;-webkit-transition-duration:.25s;-moz-transition-duration:.25s;-o-transition-duration:.25s;transition-duration:.25s}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide-active{opacity:1;transform:scale(100%)}.spectra-image-gallery__control-lightbox--thumbnails .swiper-slide img{border-radius:3px}.spectra-image-gallery__control-lightbox--count{position:absolute;z-index:999}.spectra-image-gallery__control-lightbox--close{position:absolute;cursor:pointer;padding:0;background-color:rgba(0,0,0,0);border:none;outline:0;line-height:0;z-index:999;transition:transform 500ms}.spectra-image-gallery__control-lightbox--close:hover,.spectra-image-gallery__control-lightbox--close:focus,.spectra-image-gallery__control-lightbox--close:focus-visible{background-color:rgba(0,0,0,0);transform:scale(1.25)}.spectra-image-gallery__iso-ref-wrapper{-ms-overflow-style:none;scrollbar-width:none}.spectra-image-gallery__iso-ref-wrapper::-webkit-scrollbar{display:none}@media(max-width: 976px){.spectra-image-gallery__layout--grid-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-tab-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-tab-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-tab-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-tab-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-tab-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-tab-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-tab-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-tab-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-tab-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-tab-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}@media(max-width: 767px){.spectra-image-gallery__layout--grid-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--grid-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--isogrid-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--isogrid-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--isogrid-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--isogrid-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--isogrid-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--isogrid-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--isogrid-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--isogrid-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--masonry-col-mob-1 .spectra-image-gallery__media-wrapper--isotope{width:100%}.spectra-image-gallery__layout--masonry-col-mob-2 .spectra-image-gallery__media-wrapper--isotope{width:50%}.spectra-image-gallery__layout--masonry-col-mob-3 .spectra-image-gallery__media-wrapper--isotope{width:33.33%}.spectra-image-gallery__layout--masonry-col-mob-4 .spectra-image-gallery__media-wrapper--isotope{width:25%}.spectra-image-gallery__layout--masonry-col-mob-5 .spectra-image-gallery__media-wrapper--isotope{width:20%}.spectra-image-gallery__layout--masonry-col-mob-6 .spectra-image-gallery__media-wrapper--isotope{width:16.66%}.spectra-image-gallery__layout--masonry-col-mob-7 .spectra-image-gallery__media-wrapper--isotope{width:14.28%}.spectra-image-gallery__layout--masonry-col-mob-8 .spectra-image-gallery__media-wrapper--isotope{width:12.5%}.spectra-image-gallery__layout--tiled-col-mob-1{grid-template-columns:repeat(1, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2{grid-template-columns:repeat(2, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-2 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3{grid-template-columns:repeat(3, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-3 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4{grid-template-columns:repeat(4, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-4 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5{grid-template-columns:repeat(5, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-5 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6{grid-template-columns:repeat(6, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-6 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7{grid-template-columns:repeat(7, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-7 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8{grid-template-columns:repeat(8, minmax(0, 1fr))}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper{position:relative;min-width:0}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--wide{grid-column:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--tall{grid-row:span 2}.spectra-image-gallery__layout--tiled-col-mob-8 .spectra-image-gallery__media-wrapper--focus{grid-row:span 2;grid-column:span 2}}.entry-content .wp-block-uagb-image-gallery .uagb-image-gallery__link{text-decoration:none}body .wp-block-post-content>.wp-block-uagb-image-gallery+.spectra-image-gallery__control-lightbox{margin-block-start:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.uagb-block-37fa2257.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-37fa2257 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-37fa2257 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-37fa2257 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-37fa2257 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-37fa2257 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-37fa2257 .spectra-image-gallery__iso-ref-wrapper{overflow: auto;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}@media only screen and (max-width: 976px) {.uagb-block-37fa2257.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-37fa2257 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-37fa2257 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}}@media only screen and (max-width: 767px) {.uagb-block-37fa2257.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-37fa2257 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-37fa2257 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-37fa2257 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-37fa2257 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-37fa2257 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-37fa2257+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}}.uagb-block-86bebe04.wp-block-uagb-image-gallery{padding:    ;visibility: hidden;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows svg{fill: #007cba;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -24px;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -24px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: #007cba;}.uagb-block-86bebe04 .spectra-image-gallery__control-dots li button::before{color: #007cba;}.uagb-block-86bebe04 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__control-loader div{width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-86bebe04 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;font-style: normal;text-decoration: none;}.uagb-block-86bebe04 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: blur(1px);backdrop-filter: blur(1px);box-shadow: 0 0 transparent;}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: blur(5px);backdrop-filter: blur(5px);box-shadow: 0 0 transparent;}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: blur(5px);backdrop-filter: blur(5px);box-shadow: 0 0 transparent;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail{-webkit-filter: grayscale(100%);filter: grayscale(100%);transform: scale3d(1.005, 1.005, 1.005);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-86bebe04 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;transform: scale3d(1.1, 1.1, 1.1);}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}@media only screen and (max-width: 976px) {.uagb-block-86bebe04.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-86bebe04 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-86bebe04 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--tiled{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}}@media only screen and (max-width: 767px) {.uagb-block-86bebe04.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-86bebe04 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-86bebe04 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-86bebe04 .spectra-image-gallery__layout--grid{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry{margin: -4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 4px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -8px;}.uagb-block-86bebe04 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 8px;}.uagb-block-86bebe04 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-86bebe04+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-swiper{position:relative;overflow:hidden}.uagb-slider-container{position:relative;width:100%;min-width:0;transition:box-shadow .2s ease}.uagb-slider-container .swiper-notification{left:0;opacity:0;pointer-events:none;position:absolute;top:0;z-index:-1000}.uagb-slider-container .swiper-button-next.swiper-button-disabled,.uagb-slider-container .swiper-button-prev.swiper-button-disabled{pointer-events:all}.uagb-slider-container .swiper-pagination.swiper-pagination-bullets{max-width:100%}.uagb-slider-container .swiper-button-prev,.uagb-slider-container .swiper-button-next{border-style:none;background:#efefef}.uagb-slider-container.slider-focus-mode .swiper-slide::before{content:\"\";position:absolute;left:0;right:0;top:0;bottom:0;height:100%;width:100%;z-index:99;transition-property:background}.uagb-slider-container.slider-focus-mode .swiper-slide.swiper-slide-active::before{pointer-events:none}\n.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-container.uagb-block-b63c2aa5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b63c2aa5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b63c2aa5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b63c2aa5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b63c2aa5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b63c2aa5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b63c2aa5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b63c2aa5{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.uagb-slider-container.uagb-block-eba92c5e{box-shadow: 0px 0px 0 #00000070;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container{border-color: #4B4F58;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-pagination-bullet{background-color: #333333;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-prev{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-next{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;color: #333333;width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-wrapper{align-items: center;min-height: 350px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-pagination{bottom: 20px;}.uagb-slider-container.uagb-block-eba92c5e:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-91d7891d .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-block-ca47486c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca47486c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca47486c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ca47486c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ca47486c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca47486c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca47486c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ca47486c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-45fa7b5f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-45fa7b5f .uagb-ifb-icon svg{fill: #333;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-45fa7b5f .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-45fa7b5f .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-45fa7b5f .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-45fa7b5f .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-45fa7b5f .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-45fa7b5f .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-45fa7b5f .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-45fa7b5f .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-45fa7b5f .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-45fa7b5f .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45fa7b5f .uagb-infobox__content-wrap{text-align: center;}.uagb-block-45fa7b5f.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-45fa7b5f .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-45fa7b5f .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}[dir=rtl] .uagb-block-45fa7b5f .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-88105e36 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-block-d8c1c607 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d8c1c607 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d8c1c607 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d8c1c607 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d8c1c607 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d8c1c607{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d8c1c607 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-d8c1c607{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-9dcf8c5a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9dcf8c5a .uagb-ifb-icon svg{fill: #333;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9dcf8c5a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9dcf8c5a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9dcf8c5a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9dcf8c5a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9dcf8c5a .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-9dcf8c5a .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-9dcf8c5a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9dcf8c5a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9dcf8c5a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9dcf8c5a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9dcf8c5a .uagb-infobox__content-wrap{text-align: center;}.uagb-block-9dcf8c5a.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-9dcf8c5a .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-9dcf8c5a .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}[dir=rtl] .uagb-block-9dcf8c5a .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f54bbece .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-block-44a93ca6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44a93ca6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44a93ca6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44a93ca6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44a93ca6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44a93ca6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44a93ca6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-44a93ca6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-7c04afb7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7c04afb7 .uagb-ifb-icon svg{fill: #333;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7c04afb7 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7c04afb7 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7c04afb7 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7c04afb7 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7c04afb7 .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-7c04afb7 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-7c04afb7 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7c04afb7 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7c04afb7 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7c04afb7 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7c04afb7 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-7c04afb7.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7c04afb7 .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .wp-block-button.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{padding-top: 12px;padding-bottom: 12px;padding-left: 24px;padding-right: 24px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-7c04afb7 .uagb-infobox-cta-link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}[dir=rtl] .uagb-block-7c04afb7 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b63c2aa5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b63c2aa5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b63c2aa5{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-slider-container.uagb-block-eba92c5e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-91d7891d .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca47486c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca47486c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ca47486c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45fa7b5f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-45fa7b5f .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-88105e36 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d8c1c607{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d8c1c607 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-d8c1c607{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9dcf8c5a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-9dcf8c5a .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f54bbece .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44a93ca6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44a93ca6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-44a93ca6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7c04afb7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7c04afb7 .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-b63c2aa5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b63c2aa5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b63c2aa5{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-slider-container.uagb-block-eba92c5e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next:after{font-size: 16px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-prev{left: -20px;}.uagb-slider-container.uagb-block-eba92c5e .swiper-button-next{right: -20px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-prev{width: 46px;height: 46px;line-height: 46px;}.uagb-slider-container.uagb-block-eba92c5e.uagb-slider-container .swiper-button-next{width: 46px;height: 46px;line-height: 46px;}.uagb-block-91d7891d .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ca47486c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ca47486c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ca47486c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-45fa7b5f .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-45fa7b5f .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-45fa7b5f .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-45fa7b5f.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-88105e36 .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d8c1c607{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d8c1c607 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-d8c1c607{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9dcf8c5a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9dcf8c5a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-9dcf8c5a .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-9dcf8c5a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-f54bbece .swiper-content{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44a93ca6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44a93ca6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-44a93ca6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7c04afb7 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7c04afb7 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7c04afb7 .uagb-infobox-cta-link{border-style: solid;border-color: #333;}[dir=rtl] .uagb-block-7c04afb7.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-89ce3d03 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89ce3d03 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89ce3d03 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-89ce3d03 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-89ce3d03 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-89ce3d03{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89ce3d03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-89ce3d03{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-89ce3d03{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89ce3d03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-89ce3d03{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-89ce3d03{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-89ce3d03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-89ce3d03{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.uagb-block-3ad51b97.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-3ad51b97.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-3ad51b97.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-349f9810.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-349f9810.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-349f9810.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-349f9810.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uagb-block-10bc4efe.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-10bc4efe.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-10bc4efe.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-a27a7eca.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a27a7eca.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a27a7eca.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a27a7eca.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}\";s:2:\"js\";s:3468:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'DOMContentLoaded', function() {\n\tUAGBLottie._run( {\"block_id\":\"09cf852e\",\"jsonLottie\":\"\",\"lottieURl\":\"\",\"lottieSource\":\"\",\"height\":\"\",\"heightTablet\":\"\",\"heightMob\":\"\",\"width\":\"\",\"widthTablet\":\"\",\"widthMob\":\"\",\"backgroundColor\":\"\",\"backgroundHColor\":\"\",\"loop\":true,\"speed\":1,\"reverse\":false,\"playOn\":\"none\"}, 'uagb-block-09cf852e' );\n});\nvar selector = document.querySelectorAll( '.uagb-block-b4075b93' );\nif ( selector.length > 0 ) {\n\n\tvar blockquote__tweet = selector[0].getElementsByClassName(\"uagb-blockquote__tweet-button\");\n\n\tif ( blockquote__tweet.length > 0 ) {\n\n\t\tblockquote__tweet[0].addEventListener(\"click\",function(){\t\n\t\t\tvar request_url = \"https:\/\/twitter.com\/intent\/tweet?text=%3Cstrong%3Edes+livres+qui+b%C3%A9nissent%3C%2Fstrong%3E+%E2%80%94+Author+Name&url=https%3A%2F%2Foliviaoged.com%3Fcurrency%3Deur%2Ffeed%2Fpage%2F95%2Ffeed%2Fpage%2F48%2F%2Fcart%2F%3Fcurrency%3Deur%252Ffeed%252Fpage%252F95%252Ffeed%252Fpage%252F48%252F\";\n\t\t\twindow.open( request_url );\n\t\t});\n\t}\n}\njQuery(document).ready(function () {\n\t\t\t\tlet scope = jQuery(\".wp-block-uagb-image-gallery.uagb-block-86bebe04\");\n\t\t\t\tif ( scope.length ) { \n\t\t\t\t\tscope.css(\"visibility\", \"visible\");\n\t\t\t\t\tlet getSlickCarousel = scope.find(\".uagb-slick-carousel\");\n\t\t\t\t\tif( getSlickCarousel.length ) {\n\t\t\t\t\t\tgetSlickCarousel.slick({\"arrows\":true,\"dots\":true,\"initialSlide\":0,\"infinite\":true,\"autoplay\":true,\"autoplaySpeed\":2000,\"pauseOnHover\":true,\"speed\":500,\"slidesToShow\":1,\"prevArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-prev slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z'><\/path><\/svg><\/button>\",\"nextArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-next slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='24' height='24'><path d='M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z'><\/path><\/svg><\/button>\",\"rtl\":false,\"responsive\":[{\"breakpoint\":1024,\"settings\":{\"slidesToShow\":3}},{\"breakpoint\":767,\"settings\":{\"slidesToShow\":2}}]});\n\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t});window.addEventListener(\"DOMContentLoaded\", function(){\n\tvar swiper = new Swiper( \".uagb-block-eba92c5e .uagb-swiper\",\n\t\t{\"autoplay\":{\"delay\":3000,\"disableOnInteraction\":false,\"pauseOnMouseEnter\":true,\"stopOnLastSlide\":false},\"loop\":true,\"speed\":800,\"effect\":\"slide\",\"direction\":\"horizontal\",\"flipEffect\":{\"slideShadows\":false},\"fadeEffect\":{\"crossFade\":true},\"pagination\":{\"el\":\".uagb-block-eba92c5e .swiper-pagination\",\"clickable\":true,\"hideOnClick\":false},\"navigation\":{\"nextEl\":\".uagb-block-eba92c5e .swiper-button-next\",\"prevEl\":\".uagb-block-eba92c5e .swiper-button-prev\"},\"breakpoints\":{\"976\":{\"slidesPerView\":1,\"spaceBetween\":10},\"767\":{\"slidesPerView\":1,\"spaceBetween\":10},\"320\":{\"slidesPerView\":1,\"spaceBetween\":10}}}\t);\n});\n\n });\";s:18:\"current_block_list\";a:29:{i:0;s:14:\"core\/shortcode\";i:1;s:13:\"surecart\/cart\";i:2;s:20:\"surecart\/cart-header\";i:3;s:19:\"surecart\/cart-items\";i:4;s:20:\"surecart\/cart-coupon\";i:5;s:22:\"surecart\/cart-subtotal\";i:6;s:28:\"surecart\/cart-bump-line-item\";i:7;s:20:\"surecart\/cart-submit\";i:8;s:17:\"core\/latest-posts\";i:9;s:15:\"core\/categories\";i:10;s:14:\"core\/paragraph\";i:11;s:10:\"core\/image\";i:12;s:10:\"uagb\/image\";i:13;s:18:\"getwid\/post-slider\";i:14;s:18:\"uagb\/post-carousel\";i:15;s:32:\"mailpoet\/subscription-form-block\";i:16;s:11:\"uagb\/lottie\";i:17;s:10:\"core\/cover\";i:18;s:28:\"woocommerce\/product-category\";i:19;s:15:\"uagb\/blockquote\";i:21;s:25:\"uagb\/animations-extension\";i:22;s:18:\"uagb\/image-gallery\";i:23;s:21:\"yoast-seo\/breadcrumbs\";i:24;s:14:\"uagb\/container\";i:25;s:11:\"uagb\/slider\";i:26;s:17:\"uagb\/slider-child\";i:28;s:13:\"uagb\/info-box\";i:29;s:18:\"gutenkit\/container\";i:30;s:21:\"uagb\/advanced-heading\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788362161\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"mailpoet_newsletter_max":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"","author_link":"https:\/d156afa3d1075f06\/d156afa3d1075f06oliviaoged.com\/d156afa3d1075f06en\/d156afa3d1075f06author\/d156afa3d1075f06"},"uagb_comment_info":0,"uagb_excerpt":null,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PbLW8-2Yr","_links":{"self":[{"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/pages\/11435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/comments?post=11435"}],"version-history":[{"count":1,"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/pages\/11435\/revisions"}],"predecessor-version":[{"id":16846,"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/pages\/11435\/revisions\/16846"}],"wp:attachment":[{"href":"https:\/\/oliviaoged.com\/en\/wp-json\/wp\/v2\/media?parent=11435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}